{"id":509,"count":1,"description":"","link":"https:\/\/www.homewiththekids.com\/blog\/tag\/slow-down\/","name":"slow down","slug":"slow-down","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>slow down Archives - Home with the Kids Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.homewiththekids.com\/blog\/tag\/slow-down\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"slow down Archives - Home with the Kids Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.homewiththekids.com\/blog\/tag\/slow-down\/\" \/>\n<meta property=\"og:site_name\" content=\"Home with the Kids Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@HomeWithTheKids\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/tag\\\/slow-down\\\/\",\"url\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/tag\\\/slow-down\\\/\",\"name\":\"slow down Archives - Home with the Kids Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/\",\"name\":\"Home with the Kids Blog\",\"description\":\"Work at Home in Progress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/#organization\",\"name\":\"Home With the Kids\",\"url\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/newlogo.png\",\"contentUrl\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/newlogo.png\",\"width\":395,\"height\":125,\"caption\":\"Home With the Kids\"},\"image\":{\"@id\":\"https:\\\/\\\/www.homewiththekids.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/homewiththekids\\\/\",\"https:\\\/\\\/x.com\\\/HomeWithTheKids\",\"https:\\\/\\\/www.instagram.com\\\/home_with_the_kids\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/hwtk\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"slow down Archives - Home with the Kids Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.homewiththekids.com\/blog\/tag\/slow-down\/","og_locale":"en_US","og_type":"article","og_title":"slow down Archives - Home with the Kids Blog","og_url":"https:\/\/www.homewiththekids.com\/blog\/tag\/slow-down\/","og_site_name":"Home with the Kids Blog","twitter_card":"summary_large_image","twitter_site":"@HomeWithTheKids","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.homewiththekids.com\/blog\/tag\/slow-down\/","url":"https:\/\/www.homewiththekids.com\/blog\/tag\/slow-down\/","name":"slow down Archives - Home with the Kids Blog","isPartOf":{"@id":"https:\/\/www.homewiththekids.com\/blog\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/www.homewiththekids.com\/blog\/#website","url":"https:\/\/www.homewiththekids.com\/blog\/","name":"Home with the Kids Blog","description":"Work at Home in Progress","publisher":{"@id":"https:\/\/www.homewiththekids.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.homewiththekids.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.homewiththekids.com\/blog\/#organization","name":"Home With the Kids","url":"https:\/\/www.homewiththekids.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.homewiththekids.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.homewiththekids.com\/blog\/wp-content\/uploads\/2016\/10\/newlogo.png","contentUrl":"https:\/\/www.homewiththekids.com\/blog\/wp-content\/uploads\/2016\/10\/newlogo.png","width":395,"height":125,"caption":"Home With the Kids"},"image":{"@id":"https:\/\/www.homewiththekids.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/homewiththekids\/","https:\/\/x.com\/HomeWithTheKids","https:\/\/www.instagram.com\/home_with_the_kids\/","https:\/\/www.pinterest.com\/hwtk\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.homewiththekids.com\/blog\/wp-json\/wp\/v2\/tags\/509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.homewiththekids.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.homewiththekids.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.homewiththekids.com\/blog\/wp-json\/wp\/v2\/posts?tags=509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}